{"id":43,"date":"2010-02-10T09:09:45","date_gmt":"2010-02-10T09:09:45","guid":{"rendered":"http:\/\/sassariscacchi.fuoriradio.com\/?p=43"},"modified":"2010-02-11T13:12:28","modified_gmt":"2010-02-11T13:12:28","slug":"mercoledi-10-febbraio","status":"publish","type":"post","link":"https:\/\/www.metodoideografico.it\/index.php\/2010\/02\/10\/mercoledi-10-febbraio\/","title":{"rendered":"Mercoled\u00ec, 10 febbraio"},"content":{"rendered":"<p><a href=\"http:\/\/sassariscacchi.fuoriradio.com\/wp-content\/uploads\/2010\/02\/caccia-al-tesoro.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-44\" title=\"caccia al tesoro\" src=\"http:\/\/sassariscacchi.fuoriradio.com\/wp-content\/uploads\/2010\/02\/caccia-al-tesoro-300x193.jpg\" alt=\"La scacchiera come mappa del &quot;tesoro&quot;\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.metodoideografico.it\/wp-content\/uploads\/2010\/02\/caccia-al-tesoro-300x193.jpg 300w, https:\/\/www.metodoideografico.it\/wp-content\/uploads\/2010\/02\/caccia-al-tesoro-1024x659.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u00a0Questa mattina sar\u00f2 impegnato con la psicomotricit\u00e0 in altre due prime elementari di altrettante scuole di Sassari: l&#8217;8\u00b0 Circolo\u00a0ed il 13\u00b0 Circolo. Sulle premesse teoriche ho gi\u00e0 scritto su <a href=\"http:\/\/scacchi012.wordpress.com\/2009\/07\/29\/psycomotion\/\">Scacchi012<\/a>, a cui rimando il lettore.<\/p>\n<p>Il potenziale di questa emergente metodologia che trae ispirazione dai lavori &#8220;pionieristici&#8221; di Alessandro Pompa e Filomena Morrone (nel Lazio) e Alessandro Dominici e Paola Russo (in Piemonte) \u00e8 veramente enorme! In questi primi mesi dell&#8217;anno scolastico ho lavorato soprattutto sull&#8217;attenzione e sulla capacit\u00e0 di elaborazione dei dati proposti, ma non sono mancati i giochi tipicamente motori e corporei&#8230; <a href=\"http:\/\/scacchi012.wordpress.com\/2010\/01\/23\/psicomot02\/\">Come ho scritto qui<\/a>!<\/p>\n<p><a href=\"http:\/\/sassariscacchi.fuoriradio.com\/wp-content\/uploads\/2010\/02\/Torre.jpg\"><\/a>\u00a0<\/p>\n<p><a href=\"http:\/\/sassariscacchi.fuoriradio.com\/wp-content\/uploads\/2010\/02\/Torre.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-45\" title=\"Torre\" src=\"http:\/\/sassariscacchi.fuoriradio.com\/wp-content\/uploads\/2010\/02\/Torre-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.metodoideografico.it\/wp-content\/uploads\/2010\/02\/Torre-300x225.jpg 300w, https:\/\/www.metodoideografico.it\/wp-content\/uploads\/2010\/02\/Torre-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/sassariscacchi.fuoriradio.com\/wp-content\/uploads\/2010\/02\/Torre.jpg\"><\/a><\/p>\n<p>Adesso stiamo lentamente passando ad un lavoro pi\u00f9 &#8220;scacchistico&#8221;: facciamo agire col corpo i movimenti particolari dei pezzi&#8230; Per esempio utilizzando la palla per il movimento della Torre; salti a pi\u00e8-pari per il Cavallo; corde per la Regina; percorsi su una sola gamba per l&#8217;Alfiere, eccetera.<\/p>\n<p><a href=\"http:\/\/sassariscacchi.fuoriradio.com\/wp-content\/uploads\/2010\/02\/Torre.jpg\"><\/a>\u00a0<\/p>\n<p><a href=\"http:\/\/sassariscacchi.fuoriradio.com\/wp-content\/uploads\/2010\/02\/Torre.jpg\"><\/a>\u00a0<\/p>\n<p><a href=\"http:\/\/sassariscacchi.fuoriradio.com\/wp-content\/uploads\/2010\/02\/Torre.jpg\"><\/a>\u00a0<\/p>\n<p><a href=\"http:\/\/sassariscacchi.fuoriradio.com\/wp-content\/uploads\/2010\/02\/Torre.jpg\"><\/a>\u00a0<\/p>\n<p><!--more--><\/p>\n<p><a href=\"http:\/\/sassariscacchi.fuoriradio.com\/wp-content\/uploads\/2010\/02\/gazebo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-46\" title=\"gazebo\" src=\"http:\/\/sassariscacchi.fuoriradio.com\/wp-content\/uploads\/2010\/02\/gazebo-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.metodoideografico.it\/wp-content\/uploads\/2010\/02\/gazebo-300x200.jpg 300w, https:\/\/www.metodoideografico.it\/wp-content\/uploads\/2010\/02\/gazebo-1024x685.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u00a0Colgo l&#8217;occasione per ringraziare tutti gli amici istruttori che mi hanno mandato messaggi al mio indirizzo di posta, spronandoli a farlo tranquillamente sul Blog: a questo serve! E voglio rispondere ad giovane istruttore che mi parlava delle difficolt\u00e0 a gestire la disciplina degli scolari&#8230; Proprio questo vuol&#8217;essere l&#8217;argomento di questo post odierno.<\/p>\n<p>\u00a0Oggi lavorer\u00f2 con la maestra Michela e la Maestra Domenica. Premetto che con bambini cos\u00ec piccoli l&#8217;apporto delle insegnanti \u00e8 fondamentale, anche per gli istruttori che possano vantare decenni di esperienza: la figura dell&#8217;insegnante \u00e8 quasi un &#8220;surrogato&#8221; di quella materna e non si pu\u00f2 conquistare la fiducia dei bambini senza l&#8217;aiuto delle maestre. Per questo io ritengo che l&#8217;ideale sia proprio il lavoro in sintonia con gli obiettivi scolastici e con le metodologie pedagogiche gi\u00e0 in atto.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <a href=\"http:\/\/sassariscacchi.fuoriradio.com\/wp-content\/uploads\/2010\/02\/Scacchi-028.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"Scacchi 028\" src=\"http:\/\/sassariscacchi.fuoriradio.com\/wp-content\/uploads\/2010\/02\/Scacchi-028-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a><\/p>\n<p>Spesso la rumorosit\u00e0 e la vivacit\u00e0 dei bambini (che in genere \u00e8 comunque segno di grande partecipazione) pu\u00f2 essere risolta solo grazie all&#8217;autorevolezza della maestra, che conosce meglio i bambini e sa fare leva sulla loro psicologia. Ci\u00f2 che manca spesso agli istruttori \u00e8 proprio la conoscenza delle dinamiche tipiche delle classi: magari non hanno difficolt\u00e0 ad entrare in sintonia con i singoli bambini, ma non sono\u00a0in grado di gestire la complessit\u00e0 del gruppo.<\/p>\n<p>Ma allo stesso tempo \u00e8 importante anche che le maestre si appassionino a questo strumento didattico, perch\u00e8 sono le prime beneficiarie di un accresciuto interesse e una maggiore capacit\u00e0 decisionale degli allievi: quando manca questo interesse l&#8217;esperienza rischia di essere troppo poco &#8220;scolastica&#8221; ed essere vissuta n\u00e8 pi\u00f9 e n\u00e8 meno come un diversivo didattico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Questa mattina sar\u00f2 impegnato con la psicomotricit\u00e0 in altre due prime elementari di altrettante scuole di Sassari: l&#8217;8\u00b0 Circolo\u00a0ed il 13\u00b0 Circolo. Sulle premesse teoriche ho gi\u00e0 scritto su Scacchi012, a cui rimando il lettore. Il potenziale di questa emergente metodologia che trae ispirazione dai lavori &#8220;pionieristici&#8221; di Alessandro Pompa e Filomena Morrone (nel Lazio) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-43","post","type-post","status-publish","format-standard","hentry","category-psicomotricita"],"_links":{"self":[{"href":"https:\/\/www.metodoideografico.it\/index.php\/wp-json\/wp\/v2\/posts\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metodoideografico.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.metodoideografico.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.metodoideografico.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.metodoideografico.it\/index.php\/wp-json\/wp\/v2\/comments?post=43"}],"version-history":[{"count":9,"href":"https:\/\/www.metodoideografico.it\/index.php\/wp-json\/wp\/v2\/posts\/43\/revisions"}],"predecessor-version":[{"id":92,"href":"https:\/\/www.metodoideografico.it\/index.php\/wp-json\/wp\/v2\/posts\/43\/revisions\/92"}],"wp:attachment":[{"href":"https:\/\/www.metodoideografico.it\/index.php\/wp-json\/wp\/v2\/media?parent=43"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.metodoideografico.it\/index.php\/wp-json\/wp\/v2\/categories?post=43"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.metodoideografico.it\/index.php\/wp-json\/wp\/v2\/tags?post=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}